{"id":5722,"date":"2016-08-03T11:51:11","date_gmt":"2016-08-03T16:51:11","guid":{"rendered":"http:\/\/www.servervoip.com\/blog\/?p=5722"},"modified":"2019-06-11T09:32:11","modified_gmt":"2019-06-11T14:32:11","slug":"como-funciona-la-telefonia-ip","status":"publish","type":"post","link":"http:\/\/www.servervoip.com\/blog\/como-funciona-la-telefonia-ip\/","title":{"rendered":"\u00bfComo funciona La Telefonia IP?"},"content":{"rendered":"<div style=\"display: none;\"\n    class=\"kk-star-ratings kksr-valign-top kksr-align-left kksr-disabled\"\n    data-id=\"5722\"\n    data-slug=\"\">\n    <div class=\"kksr-stars\">\n    <div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n    <\/div>\n    <div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"kksr-legend\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n<\/div>\n<p>Cuando hacemos una llamada telef\u00f3nica por IP, nuestra voz se digitaliza, se comprime y se env\u00eda en paquetes de datos IP.<\/p>\n<p>El enrutamiento de una llamada es la operaci\u00f3n encargada de encaminarla a trav\u00e9s de la red hasta el punto final, seleccionando el gateway VoIP mas adecuado.<\/p>\n<p>Este enrutamiento se lleva a cabo seg\u00fan unas tablas de condiciones que se programan en distintos gateways VoIP denominados Servidores de Directorio cuando los paquetes se env\u00edan a la persona con la que estamos hablando, llegando a su destino, son ensamblados de nuevo, descomprimidos y convertidos en la se\u00f1al de voz original, del mismo modo, un telefono puede llamar a otro conect\u00e1ndose a un gateway VoIP (directamente, a trav\u00e9s de central telef\u00f3nica o con llamada externa desde la calle) que digitalice y comprima la voz. Estos gateways VoIP soportan varios tel\u00e9fonos\/ conversaciones simult\u00e1neamente).<\/p>\n<p>En las instalaciones que neseciten mas entradas y salidas simultaneas que las soportadas que un solo gateway VoIP, se puede instalar mas gateways VoIP (se pueden implementar tantos como se neseciten).<\/p>\n<p>\u2022\tLa telefon\u00eda IP puede darse entre dos PC, un PC y un telefono convencional y dos tel\u00e9fonos convencionales. Analicemos los casos uno a uno:<br \/>\n\u2022\tConversaci\u00f3n entre PC y PC: Tan solo es necesario que ambos tengan un softwareespec\u00edfico que gestione la llamada telef\u00f3nica y estar conectados a una red IP, por ejemplo Internet, (siempre gratis)<br \/>\n\u2022\tConversaci\u00f3n entre PC y telefono convencional: El extremo del telefono convencional deber\u00e1 estar conectado a un Gateway que ser\u00e1 el encargado de conectar la red telef\u00f3nica convencional a la que esta conectado el telefono y la red IP. Por su parte el PC deber\u00e1 disponer de un software que gestione la llamada y estar conectado a una red IP (gratis en algunas ocasiones, depende del destino)<br \/>\n\u2022\tConversaci\u00f3n entre dos tel\u00e9fonos convencionales: Ambos tel\u00e9fonos deber\u00e1n estar conectados a sendos Gateway los cuales formar\u00e1n parte de una red IP (muy baratas)<br \/>\nCon todas las ventajas que despliega la telefon\u00eda IP y sus desventajas disminuyendo a pasos agigantados, no parece dif\u00edcil asegurar que el futuro de la telefon\u00eda pasa por las redes IP.<br \/>\nEn telefon\u00eda IP se piensa en una Backbone (especie de troncal) de alta velociadad no bloqueante para garantizar la calidad de servicio mediante herramientas ( redes ATM) o mediante \u201cFuerzaBruta\u201d (en redes Gigabit como la de iplan).<br \/>\n En este sistema se aplica el concepto decarrier-grade. Este concepto puede incluir varios aspectos:<br \/>\n\u2022\tredundancia de equipamiento para lograr disponibilidad elevada<br \/>\n\u2022\tCalidad vocal garantizada (bajos indicadores de errores, de retardo, de jitter y de eco<\/p>\n<p>[rev_slider captions]<br \/>\n[rev_slider ServerVoip]<br \/>\n&nbsp;<\/p>\n<hr \/>\n<p><strong>\u00bfEN QU\u00c9 SE DIFERENCIA LA TELEFON\u00cdA IP DE LA TELEFON\u00cdA NORMAL?<\/strong><\/p>\n<p>En una llamada telef\u00f3nica normal, la centralita telef\u00f3nica establece una conexi\u00f3n permanente entre ambos interlocutores, conexi\u00f3n que e utiliza para llevar las se\u00f1ales de voz. En una llamada telef\u00f3nica por IP, los paquetes de datos, que contienen la se\u00f1al de voz digitalizada y comprimida, se env\u00edan a trav\u00e9s de Internet a la dilecci\u00f3n IP del destinatario. Cada paquete puede utilizar un camino para llegar, estan compartiendo un medio, una red de datos. Cuando llegan a su destino son ordenados y convertidos de nuevo en se\u00f1al de voz.<\/p>\n<p><strong>COMPONENTES DE TELEFON\u00cdA CON INTERNET EN PROTOCOL(IP)<\/strong><\/p>\n<p>1. Terminales<\/p>\n<p>2. Gateway<\/p>\n<p>3. Gatekeeper<\/p>\n<p>4. Multipoint Control Unit (MCU)<\/p>\n<p><strong>TERMINALES<\/strong><\/p>\n<p>Los terminales son puntos finales de comunicaci\u00f3n, proporciona comunicaci\u00f3n en tiempo real bidireccional. Los componentes de los terminales son las siguientes:<\/p>\n<p> H.323 : esta parte del Terminal tiene la funci\u00f3n de soportar la voz del proceso que se esta realizando con el uso del Terminal , tambi\u00e9n sirve de soporte para el video de una imagen y los datos transmitidos . Esta parte del Terminal se usa mayormente para un videoconferencia.<br \/>\nH.245 : es un aparte del Terminal que es usado para negociar el uso del canal ay las capacidades, tambi\u00e9n es usada para un videoconferencia<br \/>\nQ.931 : se usa para la se\u00f1alizaci\u00f3n y configuraci\u00f3n de llamada<br \/>\nRAS(Registraci\u00f3n \/ Admisi\u00f3n \/ Estatus) : esta es un protocolo usada para comunicar con el gatekeeper que es otro componente del tel\u00e9fono-IP<br \/>\nEste componente de la Telefon\u00eda en IP(Internet en protocolo) que tiene funci\u00f3n de realizar el proceso de transmisi\u00f3n , puede encontrarse clientes que desea utilizar sus tel\u00e9fonos convencionales y y aquellos que cambian hacia una telefon\u00eda-IP integrada con su Local de \u00c1rea Networt (LAN), que se dice tambi\u00e9n Red de \u00c1rea Local. Cuando un cliente desea instalar un servicio integrado de telefon\u00eda y datos, la red LAN es donde se conectan los terminales, los elementos de interconexi\u00f3n al exterior por la rute del otro componente que es el llamado Gateway y tambi\u00e9n se hace el uso del componente llamado Gatekeeper , en este proceso act\u00faan todos los elementos de esta tecnolog\u00eda para poder realizar llamadas tanto al exterior como al interior del pa\u00eds.<\/p>\n<p>El servicio de Telefon\u00eda IP puede ofrecerse sin necesidad de una, por ejemplo mediante l\u00edneas anales l\u00f3gicas que se conectan a la vieja FXS.<\/p>\n<p>En el caso de utilizar el LAN los terminales se comunican en forma bidireccional en tiempo real<\/p>\n<p>Para el caso de utilizar la vieja PABX se requiere instalar un Gateway de usuario, que sirve de componente para la traducci\u00f3n.<\/p>\n<p> La telefon\u00eda publica se puede observar diferencias entre un operador local y otro de larga distancia, en este caso tambi\u00e9n act\u00faan los terminales. Pero cuando nos referimos a Telefon\u00eda-IP nos ocupamos de la aplicaci\u00f3n publica local, y es en esto que se da mas usa de los terminales del usuario.<br \/>\n Todo Terminal tienen diferentes protocolos con distintos funciones y para diferentes actividades que quiera realizar el usuario.<\/p>\n<div id=\"attachment_5723\" style=\"width: 356px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-5723\" loading=\"lazy\" src=\"http:\/\/www.servervoip.com\/blog\/wp-content\/uploads\/Ordenador-Central.gif\" alt=\"Ordenador Central\" width=\"346\" height=\"197\" class=\"size-full wp-image-5723\" \/><p id=\"caption-attachment-5723\" class=\"wp-caption-text\">Ordenador Central<\/p><\/div>\n<p><strong>GATEWAY<\/strong><\/p>\n<p>El Gateway (pasarela) es una puerta de enlace , un nodo en una red inform\u00e1tica que sirve de punto de acceso a otro red, tambi\u00e9n se dice que es un dispositivo dedicado a intercomunicar sistemas de todo los protocolos incompatibles(porque es la comunicaci\u00f3n es de una red a otra )<\/p>\n<div id=\"attachment_5724\" style=\"width: 223px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-5724\" loading=\"lazy\" src=\"http:\/\/www.servervoip.com\/blog\/wp-content\/uploads\/gateway.gif\" alt=\"gateway\" width=\"213\" height=\"131\" class=\"size-full wp-image-5724\" \/><p id=\"caption-attachment-5724\" class=\"wp-caption-text\">gateway<\/p><\/div>\n<p><strong>Puerta de enlace:<\/strong><\/p>\n<p>Se dice as\u00ed porque normalmente un equipo inform\u00e1tico par dotar las maquinas de una red local (LAN), conectada de un acceso hacia una red exterior, generalmente realizando para ello operaciones de traducci\u00f3n de direcci\u00f3n hacia una IP. La capacidad de traducci\u00f3n de direcciones permite aplicar una t\u00e9cnica llamada IP Marquerading, usada muy a menudo para dar acceso a Internet , a los equipos de LAN compartiendo una \u00fanica conexi\u00f3n a Internet , y por tanto una \u00fanica IP externa. todo Gateway puede interconectar dos redes.<\/p>\n<p><strong>Nodo :<\/strong><\/p>\n<p>Es nombrado as\u00ed porque confluyen en un espacio real y parte de la conexiones de otros espacios reales o abstractos que comparten su mismos caracter\u00edsticas que a su ves tambi\u00e9n son nodos, todos estos nodos se interrelacionan entre s\u00ed de una manera no jer\u00e1rquica y conforman lo que en t\u00e9rminos sociol\u00f3gicos o matem\u00e1ticos se denominan red .<\/p>\n<p><strong>Red Inform\u00e1tica:<\/strong><\/p>\n<p>Una red de computadora tambi\u00e9n llamada red de ordenadores es un conjunto de computadoras y dispositivos conectados entre si y que comparten informaci\u00f3n (archivos), recursos con CD, diskete, impresoras, etc. Como tambi\u00e9n servicios de E-mail(Chat).<\/p>\n<p>Punto de acceso<\/p>\n<p>Se dice as\u00ed b\u00e1sicamente a los dispositivos con funciones de interconexi\u00f3n de una red con otra red.<\/p>\n<p><strong>Tipos de Gateway<\/strong><\/p>\n<p>* Gateway (GW- FXS)<\/p>\n<p>Provee con actividad entre el mundo IP y la telefon\u00eda convencional. Se conecta la PABX convencionalmente por un lado y la red de transporte por el otro lado lo que permite conectar un usuario convencional a la red de telefon\u00eda IP publica. Permite la traslaci\u00f3n de direcciones desde IP a la ITU E.164 de la red telef\u00f3nica convencional, es decir act\u00faa de interfaz desde la red IP hacia la PSTN que es una red telefon\u00eda.<\/p>\n<p>* Gateway (GW- EI)<\/p>\n<p>Esta GW se encuentra entre la red IP y la PSTN(Red Telef\u00f3nica) para interconectar distintos proveedores de telefon\u00eda mediante t\u00e9cnicas de transporte de diversos tipos, entre las funciones de GW se encuentra la conversi\u00f3n de codificaci\u00f3n vocal, la supresi\u00f3n de silencios, la supresi\u00f3n del eco y generar las conexiones a RTP ,etc.<\/p>\n<p>La finalidad o su funci\u00f3n principal es la traducci\u00f3n de todo tipo de mensajes realizados a trav\u00e9s de una red de Internet hacia un tel\u00e9fono convencional.<\/p>\n<p><strong>Los principales aplicaciones de Gateway son las siguientes:<\/strong><\/p>\n<p>Establecer enlaces con terminales telef\u00f3nicos anal\u00f3gicos conectados a una red telef\u00f3nica<br \/>\nEstablecer enlaces con terminales remotos que cumple H.320. sobre redes RDSI basadas en circuitos conmutados (SCN)<br \/>\nEstablecer enlaces con terminales remotos que cumple H.324. sobre una red telef\u00f3nica b\u00f3rica (RTB)<br \/>\nLos Gateways no se necesitan si las conexiones son entre si redes basadas en paquetes.<\/p>\n<p>Muchas funciones de Gateway son dejadas al dise\u00f1ador. Por ejemplo, el n\u00famero de terminales H323 que puede comunicar a trav\u00e9s de Gateway y no asunto de estandarizaci\u00f3n. De la misma manera el n\u00famero de conexiones con la SCN, el n\u00famero de conferencias individuales soportadas, las funciones de conversi\u00f3n de audio\/video\/datos, y la inclusi\u00f3n de funciones multipuntos son dejadas al dise\u00f1ador. Debido a la incorporaci\u00f3n de los Gate\u00e1is a la especificaci\u00f3n H323, la ITU posici\u00f3n como el pegamento que junta todos los terminales para conferencias funcionando as\u00ed todos juntos.<\/p>\n<div id=\"attachment_5725\" style=\"width: 313px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-5725\" loading=\"lazy\" src=\"http:\/\/www.servervoip.com\/blog\/wp-content\/uploads\/Proceso-de-traduccion-del-gateway.gif\" alt=\"Proceso de traducci\u00f3n del gateway\" width=\"303\" height=\"241\" class=\"size-full wp-image-5725\" \/><p id=\"caption-attachment-5725\" class=\"wp-caption-text\">Proceso de traducci\u00f3n del gateway<\/p><\/div>\n<p>Tomado de: https:\/\/telephonyip.wordpress.com\/2011\/08\/14\/%C2%BFcomo-funciona-la-telefonia-ip\/<\/p>\n<h2>Emprendiendo en la Telefon\u00eda por Internet<\/h2>\n<p><a href=\"http:\/\/www.servervoip.com\/voipswitch\"><img loading=\"lazy\" src=\"http:\/\/www.servervoip.com\/blog\/wp-content\/uploads\/empresa-de-telefonia-voip.png\" alt=\"empresa-de-telefonia-voip\" width=\"713\" height=\"449\" class=\"aligncenter size-full wp-image-4717\" \/><\/a><br \/>\n<div  data-scroll-reveal=\"ease-in 0px over 0.6s\" ><div  id='elm_5c828b6e3d573' class='jsn-bootstrap3 st-element-container clearfix st-element-button text-center' ><script type='text\/javascript'>( function ($) {\n\t\t\t\t$( document ).ready( function () {\n\t\t\t\t\t$( '.st-button-new-window' ).click( function(e){\n\t\t\t\t\t\te.preventDefault();\n\t\t\t\t\t\tvar url = $(this).attr('href');\n\n\t\t\t\t\t\tvar width = screen.availWidth * 0.75;\n\t\t\t\t\t\tvar height = screen.availHeight * 0.75;\n\t\t\t\t\t\tvar left = parseInt((screen.availWidth\/2) - (width\/2));\n\t\t\t\t\t\tvar top = parseInt((screen.availHeight\/2) - (height\/2));\n\t\t\t\t\t\tvar windowFeatures = 'width=' + width + ',height=' + height + ',status,resizable,left=' + left + ',top=' + top + 'screenX=' + left + ',screenY=' + top;\n\t\t\t\t\t\tmyWindow = window.open(url, 'subWind', windowFeatures);\n\t\t\t\t\t} );\n\t\t\t\t});\n\t\t\t})( jQuery )<\/script><a class='btn  btn-icon-text btn-style-default btn-lg  btn-blue st-button-new-window' href='http:\/\/www.servervoip.com\/voipswitch-comprar.php?server=50_promo'><i class='fa fa-shopping-cart'><\/i> SOLICITA TU SERVER AHORA ?<\/a><\/div><\/div><style id=\"style-elm_5c828b6e3d573\">#elm_5c828b6e3d573  { margin-top: -50px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}<\/style><br \/>\n&nbsp;<br \/>\nMientras Algunos se pasan Observando los Logros de Otros; T\u00da Trabajas por el Tuyo.<\/p>\n<p>Y T\u00fa, \u00bfTienes lo Que le Hace Falta para Ser un VERDADERO EMPRENDEDOR@?<\/p>\n<p>Tu Empresa de Telefon\u00eda VoIP est\u00e1 dise\u00f1ada para que administres, gestiones y monitorees sus herramientas sin complicaciones o necesidad de conocimientos t\u00e9cnicos.<\/p>\n<ul>\n<li>Genera <strong>CLIENTES<\/strong>,<\/li>\n<li>Ingresa <strong>PROVEEDORES<\/strong>,<\/li>\n<li>Forma <strong>DISTRIBUIDORES<\/strong><\/li>\n<\/ul>\n<p><strong>ServerVoip <\/strong>presenta el mejor server fisico dedicado para telefonia voip que incluye el software de telefon\u00eda ip \u00abVoipSwitch\u00bb especial para voz sobre ip.<\/p>\n<p><strong>VoipSwitch <\/strong>es la plataforma ideal para que sin necesidad de conocimientos t\u00e9cnicos crees tu propia empresa de Telefon\u00eda IP VoIP y encuentres una forma de ganar DINERO en la red siendo carrier de telefon\u00eda sobre Ip (Voip). <\/p>\n<p>Te brindamos todas las herramientas para que est\u00e9s al nivel de las grandes empresas y negocios; puedas obsequiar llamadas gratis como estrategia de marketing en fidelizaci\u00f3n a tus clientes \/ free entre tus clientes; el servidor VoIP te permite utilizar m\u00faltiples proveedores como nosotros tenemos <a href=\"http:\/\/www.alosip.com\/\" target=\"_blank\" rel=\"noopener noreferrer\"> www.alosip.com.<\/a> (carrier \/ routes) para un mismo destino, vender terminaci\u00f3n (wholesale), clientes finales (retail), etc.<\/p>\n<p>El software te proporciona todo lo que necesitas; sistema llave en mano: para crear tu empresa de telefon\u00eda IP (VoIP) bajo tu propio nombre o marca. M\u00e1s informaci\u00f3n en  <a href=\"http:\/\/marcablanca.servervoip.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">marcaBlanca.servervoip.com<\/a><\/p>\n<p>Para que CREES y DESARROLLES tu propia empresa de telefonia por internet, revisa m\u00e1s detalles en <a href=\"http:\/\/www.servervoip.com\/voipswitch\/\">VoIPSwitch<\/a><\/p>\n<hr \/>\n<h1 style=\"text-align: center;\">\u00bfQuieres Emprender por Internet?<\/h1>\n<h3 style=\"text-align: center;\">\u00abAhora Trabajar desde la Comodidad de tu Casa y Ganar Dinero por Internet&#8230; Nunca Hab\u00eda Sido tan F\u00e1cil, R\u00e1pido y con RESULTADOS Impresionantes\u00bb<\/h3>\n<p style=\"text-align: center;\">Descubre el NEGOCIO Perfecto y convi\u00e9rtete en un EMPRESARIO de \u00c9xito creando y desarrollando tu Propia Empresa de Telefon\u00eda por Internet. <strong>Suscr\u00edbete y RECIBE FREE<\/strong>:<\/p>\n<h2 style=\"text-align: center;\">\u00a1Sie7e Poderosas Razones Que Tiene el EMPRENDEDOR Exitoso para Crear su Propia Empresa de Telefon\u00eda por Internet VoIP!&#8230;<\/h2>\n<p><img loading=\"lazy\" class=\"aligncenter wp-image-1229 size-medium\" src=\"http:\/\/servimatango.com\/negocios-rentables\/wp-content\/uploads\/2015\/07\/libro-server-voip-241x300.png\" alt=\"libro server voip\" width=\"241\" height=\"300\" \/><br \/>\n<div  id='elm_5c828b0bd3fa6' class='jsn-bootstrap3 st-element-container clearfix st-element-accordion' style='-moz-border-radius-topleft: 3px;\n-webkit-border-top-left-radius: 3px;\n border-top-left-radius: 3px;; overflow:hidden; '><div class=\"panel-group\" id=\"accordion_C1sg3n\">\n\t\t\t<div class='panel panel-default' data-tag=''>\n\t\t\t\t<div class='panel-heading'>\n\t\t\t\t\t<h4 class='panel-title'>\n\t\t\t\t\t\t<a data-toggle='collapse' href='#collapseC1sg3n0'>\n\t\t\t\t\t\t\t<i class=''><\/i><img class=aligncenter src=http:\/\/servimatango.com\/negocios-rentables\/wp-content\/uploads\/2015\/07\/Boton-descarga-reporte.gif alt=Reporte width=500 height=145 \/>\n\t\t\t\t\t\t\t<i class='st-icon-accordion'><\/i>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t<\/div>\n\t\t\t\t<div id='collapseC1sg3n0' class='panel-collapse collapse '>\n\t\t\t\t  <div class='panel-body'>\n\t\t\t\t  <p><center><script type=\"text\/javascript\" src=\"http:\/\/app.getresponse.com\/view_webform.js?wid=10619501&#038;u=kSvx\"><\/script><\/center><\/p>\n\n\t\t\t\t  <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div><\/div><style id=\"style-elm_5c828b0bd3fa6\">#elm_5c828b0bd3fa6 > .panel-group > .panel > .panel-heading { border-top-right-radius: 0px;border-top-left-radius: 0px;}#elm_5c828b0bd3fa6 > .panel-group > .panel { border-radius: 0px;}#elm_5c828b0bd3fa6  { margin-top: 0px;margin-right: 0px;margin-bottom: 15px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}<\/style><\/p>\n<p><a href=\"http:\/\/www.servervoip.com\/blog\/desventajas-telefonia-ip\/\">Desventajas al Usar la Telefonia por Internet (VoIP)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando hacemos una llamada telef\u00f3nica por IP, nuestra voz se digitaliza, se comprime y se env\u00eda en paquetes de datos IP. El enrutamiento de una llamada es la operaci\u00f3n encargada de encaminarla a trav\u00e9s de la red hasta el punto final, seleccionando el gateway VoIP mas adecuado. Este enrutamiento se lleva a cabo seg\u00fan unas&#8230;<\/p>\n<p><a class=\"excerpt-read-more btn btn-primary\" href=\"http:\/\/www.servervoip.com\/blog\/como-funciona-la-telefonia-ip\/\" title=\"Read\u00bfComo funciona La Telefonia IP?\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":[],"categories":[13],"tags":[1298,1303,1302,863,121,71,1290,20,21,28,198,1268,79,17,64],"aioseo_notices":[],"_links":{"self":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/posts\/5722"}],"collection":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/comments?post=5722"}],"version-history":[{"count":0,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/posts\/5722\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/media?parent=5722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/categories?post=5722"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/tags?post=5722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}