{"id":5859,"date":"2016-08-04T11:59:09","date_gmt":"2016-08-04T16:59:09","guid":{"rendered":"http:\/\/www.servervoip.com\/blog\/?p=5859"},"modified":"2019-06-11T09:20:40","modified_gmt":"2019-06-11T14:20:40","slug":"cuando-es-interesante-tener-su-centralita-virtual-pbx-en-la-nube","status":"publish","type":"post","link":"http:\/\/www.servervoip.com\/blog\/cuando-es-interesante-tener-su-centralita-virtual-pbx-en-la-nube\/","title":{"rendered":"Cu\u00e1ndo es interesante tener su centralita virtual PBX en la nube"},"content":{"rendered":"<div style=\"display: none;\"\n    class=\"kk-star-ratings kksr-valign-top kksr-align-left kksr-disabled\"\n    data-id=\"5859\"\n    data-slug=\"\">\n    <div class=\"kksr-stars\">\n    <div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n    <\/div>\n    <div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"kksr-legend\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n<\/div>\n<p>Cuando escrib\u00ed el art\u00edculo El futuro est\u00e1 en la nube\u2026, recib\u00ed algunos comentarios muy interesantes defendiendo ambas posibilidades, algunos a favor de la nube y otros en contra. Cada cual tiene sus razones, algunas m\u00e1s objetivas y otras puramente comerciales.<\/p>\n<p>Son muchos los factores que intervienen en la duda de si optar por una PBX en la nube o alojado en las instalaciones propias, no obstante, por petici\u00f3n de un lector vamos a analizar algunas de ellas.<\/p>\n<p><strong>Coste Material<\/strong><\/p>\n<p>El primer coste que nos evitamos tener es justamente el m\u00e1s evidente: comprar el servidor.<br \/>\nHoy d\u00eda, para una PBX de una peque\u00f1a o mediana empresa de hasta 500 puestos telef\u00f3nicos no es necesario un gran equipo. Pr\u00e1cticamente cualquier sistema que adquiramos hoy es m\u00e1s que suficiente para dar cobertura a todo lo que necesitemos, no obstante, eso implica que los 400~500\u20ac nos lo tendremos que gastar en meter un procesador de 4 n\u00facleos, 8 \u00f3 16Gb de RAM y al menos una tarjeta de comunicaciones o un gateway para conectar nuestro servidor a las l\u00edneas \u201clocales\u201d de la PSTN.<\/p>\n<p>El tema de los tel\u00e9fonos a utilizar, como es algo que vamos a tener que utilizar en ambos casos, no vamos tenerlo en cuenta.<\/p>\n<p><strong>Coste Mensual<\/strong><\/p>\n<p>Si vamos a utilizar l\u00edneas f\u00edsicas, hay que contar con que, al menos en Espa\u00f1a, cada l\u00ednea anal\u00f3gica cuesta unos 15\u20ac\/mes de mantenimiento, que se convierten en 40\u20ac\/mes en el caso de una RDSI y unos 350\u20ac\/mes en el caso de un RDSI Primario.<\/p>\n<p>El coste energ\u00e9tico de mantener una PBX encendida 24 horas al d\u00eda es, utilizando una calculadora de potencia y aproximaciones, medias y dem\u00e1s, unos 300 \u20ac anuales para un servidor que consuma unos 170W a la hora, es decir, unos 25\u20ac\/mes m\u00e1s el coste energ\u00e9tico de switches y dem\u00e1s material de red que necesitemos.<\/p>\n<p>Si vamos a utilizar un Operador IP, es importante disponer de una conexi\u00f3n a Internet en condiciones proporcional al n\u00famero de llamadas m\u00e1xima que vayamos a tener en nuestro sistema. Por suerte, si disponemos de una conexi\u00f3n de fibra \u00f3ptica FTTH 100\/10 ser\u00eda ideal, o incluso mejor, una de 200\/200 que suele rondar los 50\u20ac\/mes. ?<\/p>\n<p><strong>Coste de las llamadas<\/strong><\/p>\n<p>Una de las ventajas de disponer de nuestra propia centralita PBX alojada en nuestras instalaciones es la posibilidad de utilizar tantos trunks de operadores IP como deseemos, pudiendo enviar llamadas por uno u otro operador seg\u00fan nos interese, aprovechando las mejores tarifas en funci\u00f3n del destino al que vayamos a hacer.<\/p>\n<p>En el caso de las centralitas virtuales, generalmente alojadas por operadores IP, todas las llamadas se realizar\u00e1n a trav\u00e9s de ellos, no pudiendo aprovechar las tarifas de otros operadores, aunque estas sean mejores.<\/p>\n<p>[rev_slider captions]<br \/>\n[rev_slider ServerVoip]<br \/>\n&nbsp;<\/p>\n<hr \/>\n<p><strong>Riesgo en caso de ca\u00edda<\/strong><\/p>\n<p>Nunca he sido partidario de hablar de \u201cca\u00eddas\u201d, menos a\u00fan si consideramos ca\u00eddas por igual el hecho de un corte de luz, que de internet, de que un fallo hardware.<\/p>\n<p>Tener nuestro propio servidor en nuestras instalaciones tiene bastantes riesgos de ca\u00eddas y estas dependen de muchos factores:<\/p>\n<p>Cortes de corriente: Hay sitios m\u00e1s propensos a tener cortes de luz, lo que nos llevar\u00eda a necesitar de protectores de tensi\u00f3n y SAI con capacidad para hacer frente a un corte durante un tiempo considerable.<br \/>\nGeneralmente en lugares alejados del centro urbano, las instalaciones el\u00e9ctricas suelen ser m\u00e1s antiguas y por lo tanto, las ca\u00eddas son m\u00e1s frecuentes.<br \/>\nCortes de Internet: Est\u00e1 claro que en una oficina es posible que haya alg\u00fan corte de acceso: el router se calienta, demasiada humedad en la sala donde est\u00e1n los switches y routers, etc\u2026 Estos cortes suelen ocurrir al menos 6 \u00f3 7 veces al a\u00f1o en el mejor de los casos y suelen durar un par de horas cada uno como mucho. (por supuesto, hay excepciones).<br \/>\nCortes debido al hardware: Hay casos en los que el servidor se bloquea, bien por que necesita una puesta a punto o bien por que hay que quitarle el polvo al ventilador. Tambi\u00e9n puede ocurrir que, tras alg\u00fan corte de corriente, el disco duro haya hecho \u201cpufff\u201d y hayamos perdidos todos los datos que ten\u00edamos guardados y no tuvi\u00e9ramos hecha copia de seguridad, pero eso suele ocurrir a partir del cuarto a\u00f1o, as\u00ed que este tipo de cortes son los menos comunes.<br \/>\nNo obstante, es cierto que siempre hay riesgo, y el hecho de que un servidor est\u00e9 en un datacenter especializado puede evitar bastante ciertas \u201cca\u00eddas\u201d, por lo que son menos ocasionales. Tambi\u00e9n es cierto que cuando estas ocurren, suelen ser mucho m\u00e1s duraderas y problem\u00e1ticas. Cuando en un datacenter hay un corte de corriente (que tambi\u00e9n los hay), aunque no suelen ocurrir cortes as\u00ed en varios a\u00f1os, es cierto que cuando los hay, la reparaci\u00f3n suele llevar varias horas.<\/p>\n<p>De igual manera, los servidores que se utilizan en un datacenter no tienen por qu\u00e9 ser a prueba de errores, y los discos duros tambi\u00e9n se estropean, por lo que salvo que hayamos contratado alg\u00fan tipo de seguro o que el proveedor tenga previsto ese caso, si hay un fallo hardware, tambi\u00e9n vamos a perder los datos y quedarnos sin tel\u00e9fono un buen rato mientras lo arreglan.<\/p>\n<p><strong>Entonces \u00bfcu\u00e1ndo interesa tener un servidor propio?<\/strong><\/p>\n<p>Ya hemos visto que en la mayor\u00eda de los casos, puede ser m\u00e1s interesante econ\u00f3micamente tener una centralita virtual o una PBX en la nube que tenerla en nuestras instalaciones.<\/p>\n<p>No obstante, existen casos en los que puede ser m\u00e1s interesante tenerla alojada en nuestras instalaciones:<\/p>\n<p>Cuando tengamos aplicaciones de terceros conectada a la centralita y necesitemos una conexi\u00f3n particular a ella: click2call, CRM, ERP, o aplicaciones que usen TAPI, AMI, etc\u2026<br \/>\nCuando queramos utilizar sistemas de reconocimiento de voz (ASR) o text-to-speech (TTS).<br \/>\nCuando queramos utilizar varios operadores.<br \/>\nCuando queramos conectar con las centralitas de otras sedes.<br \/>\nPor supuesto, esto no significa que si queremos hacer algo de esto no se pueda utilizar una centralita virtual, pero seguramente ser\u00e1 m\u00e1s f\u00e1cil hacerlo si la tenemos en nuestras instalaciones.<\/p>\n<p>Tomado de: https:\/\/www.sinologic.net\/blog\/2015-03\/cuando-interesa-tener-centralita-virtual-pbx-nube.html<\/p>\n<h2>Emprendiendo en la Telefon\u00eda por Internet<\/h2>\n<p><a href=\"http:\/\/www.servervoip.com\/voipswitch\"><img loading=\"lazy\" src=\"http:\/\/www.servervoip.com\/blog\/wp-content\/uploads\/empresa-de-telefonia-voip.png\" alt=\"empresa-de-telefonia-voip\" width=\"713\" height=\"449\" class=\"aligncenter size-full wp-image-4717\" \/><\/a><br \/>\n<div  data-scroll-reveal=\"ease-in 0px over 0.6s\" ><div  id='elm_5c828b6871435' class='jsn-bootstrap3 st-element-container clearfix st-element-button text-center' ><script type='text\/javascript'>( function ($) {\n\t\t\t\t$( document ).ready( function () {\n\t\t\t\t\t$( '.st-button-new-window' ).click( function(e){\n\t\t\t\t\t\te.preventDefault();\n\t\t\t\t\t\tvar url = $(this).attr('href');\n\n\t\t\t\t\t\tvar width = screen.availWidth * 0.75;\n\t\t\t\t\t\tvar height = screen.availHeight * 0.75;\n\t\t\t\t\t\tvar left = parseInt((screen.availWidth\/2) - (width\/2));\n\t\t\t\t\t\tvar top = parseInt((screen.availHeight\/2) - (height\/2));\n\t\t\t\t\t\tvar windowFeatures = 'width=' + width + ',height=' + height + ',status,resizable,left=' + left + ',top=' + top + 'screenX=' + left + ',screenY=' + top;\n\t\t\t\t\t\tmyWindow = window.open(url, 'subWind', windowFeatures);\n\t\t\t\t\t} );\n\t\t\t\t});\n\t\t\t})( jQuery )<\/script><a class='btn  btn-icon-text btn-style-default btn-lg  btn-blue st-button-new-window' href='http:\/\/www.servervoip.com\/voipswitch-comprar.php?server=50_promo'><i class='fa fa-shopping-cart'><\/i> SOLICITA TU SERVER AHORA ?<\/a><\/div><\/div><style id=\"style-elm_5c828b6871435\">#elm_5c828b6871435  { margin-top: -50px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}<\/style><br \/>\n&nbsp;<br \/>\nMientras Algunos se pasan Observando los Logros de Otros; T\u00da Trabajas por el Tuyo.<\/p>\n<p>Y T\u00fa, \u00bfTienes lo Que le Hace Falta para Ser un VERDADERO EMPRENDEDOR@?<\/p>\n<p>Tu Empresa de Telefon\u00eda VoIP est\u00e1 dise\u00f1ada para que administres, gestiones y monitorees sus herramientas sin complicaciones o necesidad de conocimientos t\u00e9cnicos.<\/p>\n<ul>\n<li>Genera <strong>CLIENTES<\/strong>,<\/li>\n<li>Ingresa <strong>PROVEEDORES<\/strong>,<\/li>\n<li>Forma <strong>DISTRIBUIDORES<\/strong><\/li>\n<\/ul>\n<p><strong>ServerVoip <\/strong>presenta el mejor server fisico dedicado para telefonia voip que incluye el software de telefon\u00eda ip \u00abVoipSwitch\u00bb especial para voz sobre ip.<\/p>\n<p><strong>VoipSwitch <\/strong>es la plataforma ideal para que sin necesidad de conocimientos t\u00e9cnicos crees tu propia empresa de Telefon\u00eda IP VoIP y encuentres una forma de ganar DINERO en la red siendo carrier de telefon\u00eda sobre Ip (Voip). <\/p>\n<p>Te brindamos todas las herramientas para que est\u00e9s al nivel de las grandes empresas y negocios; puedas obsequiar llamadas gratis como estrategia de marketing en fidelizaci\u00f3n a tus clientes \/ free entre tus clientes; el servidor VoIP te permite utilizar m\u00faltiples proveedores como nosotros tenemos <a href=\"http:\/\/www.alosip.com\/\" target=\"_blank\" rel=\"noopener noreferrer\"> www.alosip.com.<\/a> (carrier \/ routes) para un mismo destino, vender terminaci\u00f3n (wholesale), clientes finales (retail), etc.<\/p>\n<p>El software te proporciona todo lo que necesitas; sistema llave en mano: para crear tu empresa de telefon\u00eda IP (VoIP) bajo tu propio nombre o marca. M\u00e1s informaci\u00f3n en  <a href=\"http:\/\/marcablanca.servervoip.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">marcaBlanca.servervoip.com<\/a><\/p>\n<p>Para que CREES y DESARROLLES tu propia empresa de telefonia por internet, revisa m\u00e1s detalles en <a href=\"http:\/\/www.servervoip.com\/voipswitch\/\">VoIPSwitch<\/a><\/p>\n<hr \/>\n<h1 style=\"text-align: center;\">\u00bfQuieres Emprender por Internet?<\/h1>\n<h3 style=\"text-align: center;\">\u00abAhora Trabajar desde la Comodidad de tu Casa y Ganar Dinero por Internet&#8230; Nunca Hab\u00eda Sido tan F\u00e1cil, R\u00e1pido y con RESULTADOS Impresionantes\u00bb<\/h3>\n<p style=\"text-align: center;\">Descubre el NEGOCIO Perfecto y convi\u00e9rtete en un EMPRESARIO de \u00c9xito creando y desarrollando tu Propia Empresa de Telefon\u00eda por Internet. <strong>Suscr\u00edbete y RECIBE FREE<\/strong>:<\/p>\n<h2 style=\"text-align: center;\">\u00a1Sie7e Poderosas Razones Que Tiene el EMPRENDEDOR Exitoso para Crear su Propia Empresa de Telefon\u00eda por Internet VoIP!&#8230;<\/h2>\n<p><img loading=\"lazy\" class=\"aligncenter wp-image-1229 size-medium\" src=\"http:\/\/servimatango.com\/negocios-rentables\/wp-content\/uploads\/2015\/07\/libro-server-voip-241x300.png\" alt=\"libro server voip\" width=\"241\" height=\"300\" \/><br \/>\n<div  id='elm_5c828b0bd3fa6' class='jsn-bootstrap3 st-element-container clearfix st-element-accordion' style='-moz-border-radius-topleft: 3px;\n-webkit-border-top-left-radius: 3px;\n border-top-left-radius: 3px;; overflow:hidden; '><div class=\"panel-group\" id=\"accordion_60U9o9\">\n\t\t\t<div class='panel panel-default' data-tag=''>\n\t\t\t\t<div class='panel-heading'>\n\t\t\t\t\t<h4 class='panel-title'>\n\t\t\t\t\t\t<a data-toggle='collapse' href='#collapse60U9o90'>\n\t\t\t\t\t\t\t<i class=''><\/i><img class=aligncenter src=http:\/\/servimatango.com\/negocios-rentables\/wp-content\/uploads\/2015\/07\/Boton-descarga-reporte.gif alt=Reporte width=500 height=145 \/>\n\t\t\t\t\t\t\t<i class='st-icon-accordion'><\/i>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t<\/div>\n\t\t\t\t<div id='collapse60U9o90' class='panel-collapse collapse '>\n\t\t\t\t  <div class='panel-body'>\n\t\t\t\t  <p><center><script type=\"text\/javascript\" src=\"http:\/\/app.getresponse.com\/view_webform.js?wid=10619501&#038;u=kSvx\"><\/script><\/center><\/p>\n\n\t\t\t\t  <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div><\/div><style id=\"style-elm_5c828b0bd3fa6\">#elm_5c828b0bd3fa6 > .panel-group > .panel > .panel-heading { border-top-right-radius: 0px;border-top-left-radius: 0px;}#elm_5c828b0bd3fa6 > .panel-group > .panel { border-radius: 0px;}#elm_5c828b0bd3fa6  { margin-top: 0px;margin-right: 0px;margin-bottom: 15px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}<\/style><\/p>\n<p><a href=\"http:\/\/www.servervoip.com\/blog\/desventajas-telefonia-ip\/\">Desventajas al Usar la Telefonia por Internet (VoIP)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando escrib\u00ed el art\u00edculo El futuro est\u00e1 en la nube\u2026, recib\u00ed algunos comentarios muy interesantes defendiendo ambas posibilidades, algunos a favor de la nube y otros en contra. Cada cual tiene sus razones, algunas m\u00e1s objetivas y otras puramente comerciales. Son muchos los factores que intervienen en la duda de si optar por una PBX&#8230;<\/p>\n<p><a class=\"excerpt-read-more btn btn-primary\" href=\"http:\/\/www.servervoip.com\/blog\/cuando-es-interesante-tener-su-centralita-virtual-pbx-en-la-nube\/\" title=\"ReadCu\u00e1ndo es interesante tener su centralita virtual PBX en la nube\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":[],"categories":[13],"tags":[857,1282,1015,1400,1088,1294,1283,1028,21,28,17],"aioseo_notices":[],"_links":{"self":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/posts\/5859"}],"collection":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/comments?post=5859"}],"version-history":[{"count":0,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/posts\/5859\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/media?parent=5859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/categories?post=5859"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/tags?post=5859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}