{"id":6004,"date":"2016-08-05T13:24:56","date_gmt":"2016-08-05T18:24:56","guid":{"rendered":"http:\/\/www.servervoip.com\/blog\/?p=6004"},"modified":"2019-06-11T09:03:36","modified_gmt":"2019-06-11T14:03:36","slug":"funcionalidad-de-sip","status":"publish","type":"post","link":"http:\/\/www.servervoip.com\/blog\/funcionalidad-de-sip\/","title":{"rendered":"Funcionalidad de SIP"},"content":{"rendered":"<div style=\"display: none;\"\n    class=\"kk-star-ratings kksr-valign-top kksr-align-left kksr-disabled\"\n    data-id=\"6004\"\n    data-slug=\"\">\n    <div class=\"kksr-stars\">\n    <div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n    <\/div>\n    <div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"kksr-legend\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n<\/div>\n<p>El protocolo inicial de sesi\u00f3n es un protocolo de control de la capa de aplicaci\u00f3n que puede establecer, modificar y terminar sesiones multimedia o llamadas. Estas sesiones multimedia incluyen conferencias multimedia, aprendizaje a distancia, telefon\u00eda Internet y aplicaciones similares. SIP puede invitar a ambas personas y \u201crobots\u201d tal como servicio de almacenamiento de medios.  SIP puede invitar tanto sesiones unicast o multicast, el iniciador no tiene que ser un miembro de una sesi\u00f3n a la cual se le esta invitando. Medios y participantes pueden ser agregados a una sesi\u00f3n existente.<\/p>\n<p>SIP puede ser usado para iniciar sesiones tanto como invitar a miembros a sesiones que han sido anunciadas y establecidas por otros miembros. Las sesiones pueden ser anunciadas usando protocolos multidifusion como SAP, mail, grupos, paginas Web o directorios (LDAP) y muchas otras formas.<\/p>\n<p>SIP transparentemente soporta mapeado y redireccionamiento de servicios, permitiendo la implementaci\u00f3n de ISDN y servicios de subscripci\u00f3n de red de telefon\u00eda inteligente. Estas facilidades tambi\u00e9n permiten la movilidad personal.<\/p>\n<p>En el lenguaje de servicios de telecomunicaciones de red inteligente, esto es definido como:\u201d Movilidad personal es la habilidad del usuario final para originar y recibir llamadas y acceso de servicios subscritos de telecomunicaciones sobre cualquier terminal en cualquier lugar, y la habilidad de la red para identificar a los usuarios finales dondequiera que se encuentren. La movilidad personal esta basado sobre el uso de una identificaci\u00f3n personal (por ejemplo un numero personal)\u201d. <\/p>\n<p> La movilidad personal complementa la movilidad de la terminal por ejemplo la habilidad para mantener comunicaci\u00f3n cuando se mueve una sencilla terminal  de una sub-red a otra.<\/p>\n<p>[rev_slider captions]<br \/>\n[rev_slider ServerVoip]<br \/>\n&nbsp;<\/p>\n<hr \/>\n<p>SIP soporta cinco facetas de establecimiento y terminaci\u00f3n de comunicaciones multimedia:<\/p>\n<p>\u2022\tSitio de usuario: Determinaci\u00f3n del sistema final para ser usado para la comunicaci\u00f3n.<br \/>\n\u2022\tCapacidades de usuario: Determinaci\u00f3n del medio y par\u00e1metros del medio (audio\/video) para ser usados.<br \/>\n\u2022\tDisponibilidad de usuario: Determinaci\u00f3n de buena voluntad de la llamada para ser empleada en las comunicaciones<br \/>\n\u2022\tEstablecimiento de la llamada: \u201ctimbrado\u201d, establecimiento de los par\u00e1metros de llamada tanto en la llamada como la sesi\u00f3n  de llamadas.<br \/>\n\u2022\tManejo de llamada: Incluyendo transferencia y terminaci\u00f3n de llamadas.<\/p>\n<p>SIP adem\u00e1s puede iniciar llamadas multi-sesiones usando una Unidad de Control Multipunto (MCU) o enredado completo de interconexiones en lugar de multicast. Gateways de telefon\u00eda sobre Internet que conectan las sesiones de llamadas con la Red P\u00fablica Telef\u00f3nica Conmutada pueden usar SIP para establecer llamadas entre ellos.<\/p>\n<p>SIP esta dise\u00f1ado como una parte de la  IETF de datos multimedia y el control de arquitectura actualmente incorporando protocolos como RSVP para las fuentes de reserva de red, el protocolo de transporte en tiempo real (RTP) para transportar datos en tiempo real y proveer retroalimentaci\u00f3n de calidad del servicio,  protocolo en tiempo real de streaming (RTSP) para controlar la entrega o media streaming, el protocolo de anuncio de sesi\u00f3n (SAP) para anunciar las sesiones multimedia v\u00eda multidifusion (multicast) y el protocolo de descripci\u00f3n de sesi\u00f3n (SDP) para describir las sesiones multimedia. Sin embargo, la funcionalidad y operaci\u00f3n de SIP no depende de ninguno de estos protocolos.<\/p>\n<p>SIP puede ser usado conjuntamente con otro establecimiento de llamada y otro tipo de protocolos de se\u00f1alizaci\u00f3n. En ese modo un sistema final usa intercambios SIP para determinar la direcci\u00f3n apropiada del sistema final y el protocolo de esa direcci\u00f3n dada que es un protocolo independiente.  Por ejemplo SIP puede ser usado para determinar que la sesi\u00f3n puede ser alcanzada v\u00eda H.323 obteniendo la direcci\u00f3n del Gateway H.245, la direcci\u00f3n del usuario y entonces usar H.225 para establecer la llamada.<\/p>\n<p>En otro ejemplo, SIP podr\u00eda ser usado para determinar que la llamada es lograda v\u00eda PSTN (Red Telef\u00f3nica Publica Conmutada) e indicar el numero telef\u00f3nico que ser\u00e1 llamado con la posible sugerencia de ser usado un Gateway de Internet a Red Telef\u00f3nica Publica Conmutada).<br \/>\n SIP no ofrece servicio de control de conferencia como control de fondo o votado  y no prescribe como una conferencia que ser\u00e1 administrada, pero SIP puede ser usado para introducir protocolos de control conferencia. SIP no designa direcciones mutidifusion.<br \/>\nSIP puede invitar usuarios a sesiones con o sin una reservaci\u00f3n. SIP no reserva fuentes, pero puede convenir con el sistema invitado la informaci\u00f3n necesaria para hacer esto.<\/p>\n<p>Tomado de:<br \/>\nDominguez, U, &#038; Hernandez, R. (xxxx). Principio de Funcionamiento de VoIP (Tesina de Titulaci\u00f3n).<\/p>\n<p>Fuente:<br \/>\nwww.icicm.com\/files\/VOIP.doc<\/p>\n<h2>Telefon\u00eda VoIP con SoftSwitch<\/h2>\n<p><strong>ServerVoIP<\/strong> te proporciona todas las herramientas necesarias para que crees y desarrolles <strong>tu negocio de comunicaci\u00f3n por internet.<\/strong><\/p>\n<p>Pertenece al Selecto Grupo de Emprendedores que decidieron cambiar su vida invirtiendo en un <strong>Server con ServerVoIP.<\/strong><\/p>\n<p><a href=\"http:\/\/www.servervoip.com\/voipswitch-pagos\"><img loading=\"lazy\" src=\"http:\/\/www.servervoip.com\/blog\/wp-content\/uploads\/2015\/08\/tarjeta1-292x300.png\" alt=\"empresario\" width=\"292\" height=\"300\" class=\"aligncenter size-medium wp-image-4092\" \/><\/a><br \/>\n<div  data-scroll-reveal=\"ease-in 0px over 0.6s\" ><div  id='elm_5c828b621cf9c' class='jsn-bootstrap3 st-element-container clearfix st-element-button text-center' ><script type='text\/javascript'>( function ($) {\n\t\t\t\t$( document ).ready( function () {\n\t\t\t\t\t$( '.st-button-new-window' ).click( function(e){\n\t\t\t\t\t\te.preventDefault();\n\t\t\t\t\t\tvar url = $(this).attr('href');\n\n\t\t\t\t\t\tvar width = screen.availWidth * 0.75;\n\t\t\t\t\t\tvar height = screen.availHeight * 0.75;\n\t\t\t\t\t\tvar left = parseInt((screen.availWidth\/2) - (width\/2));\n\t\t\t\t\t\tvar top = parseInt((screen.availHeight\/2) - (height\/2));\n\t\t\t\t\t\tvar windowFeatures = 'width=' + width + ',height=' + height + ',status,resizable,left=' + left + ',top=' + top + 'screenX=' + left + ',screenY=' + top;\n\t\t\t\t\t\tmyWindow = window.open(url, 'subWind', windowFeatures);\n\t\t\t\t\t} );\n\t\t\t\t});\n\t\t\t})( jQuery )<\/script><a class='btn  btn-icon-text btn-style-default btn-lg  btn-blue st-button-new-window' href='http:\/\/www.servervoip.com\/voipswitch-comprar.php?server=50_promo'><i class='fa fa-shopping-cart'><\/i> SOLICITA TU SERVER AHORA \u25ba<\/a><\/div><\/div><style id=\"style-elm_5c828b621cf9c\">#elm_5c828b621cf9c  { margin-top: -50px;margin-right: 0px;margin-bottom: -20px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}<\/style><br \/>\n&nbsp;<\/p>\n<p><strong>ServerVoip <\/strong>presenta el mejor server fisico dedicado para telefonia voip que incluye el software de telefon\u00eda ip \u00abVoipSwitch\u00bb especial para voz sobre ip.<\/p>\n<p><strong>VoipSwitch <\/strong>es la plataforma ideal para que sin necesidad de conocimientos t\u00e9cnicos crees tu propia empresa de Telefon\u00eda IP VoIP y encuentres una forma de ganar DINERO en la red siendo carrier de telefon\u00eda sobre Ip (Voip). <\/p>\n<p>Te brindamos todas las herramientas para que est\u00e9s al nivel de las grandes empresas y negocios; puedas obsequiar llamadas gratis como estrategia de marketing en fidelizaci\u00f3n a tus clientes \/ free entre tus clientes; el servidor VoIP te permite utilizar m\u00faltiples proveedores como nosotros tenemos <a href=\"http:\/\/www.alosip.com\/\" target=\"_blank\"  rel=\"noopener noreferrer\">www.alosip.com.<\/a>  (carrier \/ routes) para un mismo destino, vender terminaci\u00f3n (wholesale), clientes finales (retail), etc.<\/p>\n<p>El software te proporciona todo lo que necesitas; sistema llave en mano: para crear tu empresa de telefon\u00eda IP (VoIP) bajo tu propio nombre o marca. M\u00e1s informaci\u00f3n en  <a href=\"http:\/\/marcablanca.servervoip.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">marcaBlanca.servervoip.com<\/a><\/p>\n<p>Para que CREES y DESARROLLES tu propia empresa de telefonia por internet, revisa m\u00e1s detalles en <a href=\"http:\/\/www.servervoip.com\/voipswitch\/\" >VoIPSwitch<\/a><\/p>\n<hr \/>\n<h1 style=\"text-align: center;\">\u00bfQuieres Emprender por Internet?<\/h1>\n<h3 style=\"text-align: center;\">\u00abAhora Trabajar desde la Comodidad de tu Casa y Ganar Dinero por Internet&#8230; Nunca Hab\u00eda Sido tan F\u00e1cil, R\u00e1pido y con RESULTADOS Impresionantes\u00bb<\/h3>\n<p style=\"text-align: center;\">Descubre el NEGOCIO Perfecto y convi\u00e9rtete en un EMPRESARIO de \u00c9xito creando y desarrollando tu Propia Empresa de Telefon\u00eda por Internet. <strong>Suscr\u00edbete y RECIBE FREE<\/strong>:<\/p>\n<h2 style=\"text-align: center;\">\u00a1Sie7e Poderosas Razones Que Tiene el EMPRENDEDOR Exitoso para Crear su Propia Empresa de Telefon\u00eda por Internet VoIP!&#8230;<\/h2>\n<p><img loading=\"lazy\" class=\"aligncenter wp-image-1229 size-medium\" src=\"http:\/\/servimatango.com\/negocios-rentables\/wp-content\/uploads\/2015\/07\/libro-server-voip-241x300.png\" alt=\"libro server voip\" width=\"241\" height=\"300\" \/><br \/>\n<div  id='elm_5c828b0bd3fa6' class='jsn-bootstrap3 st-element-container clearfix st-element-accordion' style='-moz-border-radius-topleft: 3px;\n-webkit-border-top-left-radius: 3px;\n border-top-left-radius: 3px;; overflow:hidden; '><div class=\"panel-group\" id=\"accordion_Z6VRV4\">\n\t\t\t<div class='panel panel-default' data-tag=''>\n\t\t\t\t<div class='panel-heading'>\n\t\t\t\t\t<h4 class='panel-title'>\n\t\t\t\t\t\t<a data-toggle='collapse' href='#collapseZ6VRV40'>\n\t\t\t\t\t\t\t<i class=''><\/i><img class=aligncenter src=http:\/\/servimatango.com\/negocios-rentables\/wp-content\/uploads\/2015\/07\/Boton-descarga-reporte.gif alt=Reporte width=500 height=145 \/>\n\t\t\t\t\t\t\t<i class='st-icon-accordion'><\/i>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t<\/div>\n\t\t\t\t<div id='collapseZ6VRV40' class='panel-collapse collapse '>\n\t\t\t\t  <div class='panel-body'>\n\t\t\t\t  <p><center><script type=\"text\/javascript\" src=\"http:\/\/app.getresponse.com\/view_webform.js?wid=10619501&#038;u=kSvx\"><\/script><\/center><\/p>\n\n\t\t\t\t  <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div><\/div><style id=\"style-elm_5c828b0bd3fa6\">#elm_5c828b0bd3fa6 > .panel-group > .panel > .panel-heading { border-top-right-radius: 0px;border-top-left-radius: 0px;}#elm_5c828b0bd3fa6 > .panel-group > .panel { border-radius: 0px;}#elm_5c828b0bd3fa6  { margin-top: 0px;margin-right: 0px;margin-bottom: 15px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}<\/style><\/p>\n<p><a href=\"http:\/\/www.servervoip.com\/blog\/bancos-en-ecuador\/\">Bancos en Ecuador para Alquilar un VoIPSwitch Server<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El protocolo inicial de sesi\u00f3n es un protocolo de control de la capa de aplicaci\u00f3n que puede establecer, modificar y terminar sesiones multimedia o llamadas. Estas sesiones multimedia incluyen conferencias multimedia, aprendizaje a distancia, telefon\u00eda Internet y aplicaciones similares. SIP puede invitar a ambas personas y \u201crobots\u201d tal como servicio de almacenamiento de medios. SIP&#8230;<\/p>\n<p><a class=\"excerpt-read-more btn btn-primary\" href=\"http:\/\/www.servervoip.com\/blog\/funcionalidad-de-sip\/\" title=\"ReadFuncionalidad de SIP\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":[],"categories":[13],"tags":[1195,1466,162,14,979,656,1495,773,1231,17],"aioseo_notices":[],"_links":{"self":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/posts\/6004"}],"collection":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/comments?post=6004"}],"version-history":[{"count":0,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/posts\/6004\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/media?parent=6004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/categories?post=6004"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/tags?post=6004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}