{"id":6899,"date":"2016-08-19T12:36:34","date_gmt":"2016-08-19T17:36:34","guid":{"rendered":"http:\/\/www.servervoip.com\/blog\/?p=6899"},"modified":"2019-06-11T07:32:57","modified_gmt":"2019-06-11T12:32:57","slug":"formato-de-los-mensajes","status":"publish","type":"post","link":"http:\/\/www.servervoip.com\/blog\/formato-de-los-mensajes\/","title":{"rendered":"Formato de los Mensajes"},"content":{"rendered":"<div style=\"display: none;\"\n    class=\"kk-star-ratings kksr-valign-top kksr-align-left kksr-disabled\"\n    data-id=\"6899\"\n    data-slug=\"\">\n    <div class=\"kksr-stars\">\n    <div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n    <\/div>\n    <div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"kksr-legend\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n<\/div>\n<p><strong>Formato de los Mensajes: <\/strong> Los mensajes que se intercambian en el protocolo SI P pueden ser peticiones o  respuestas.  Las peticiones tienen una l\u00ednea de petici\u00f3n, una serie de encabezados y un cuerpo.  Las respuestas tienen una l\u00ednea de respuesta, una serie de encabezados y un  cuerpo.  En la l\u00ednea de petici\u00f3n se indica el prop\u00f3sito de la petici\u00f3n y el destinatario de la  petici\u00f3n.  <\/p>\n<p>Las peticiones tienen distintas funciones. El prop\u00f3sito de una petici\u00f3n est\u00e1  determinado por lo que se denomina el M\u00e9todo (Method) de dicha petici\u00f3n, que no  es m\u00e1s que un identificador del prop\u00f3sito de la petici\u00f3n. En la [RFC 3261] se  definen los m\u00e9todos b\u00e1sicos del protocolo. Existen  otros m\u00e9todos definidos en  extensiones al protocolo SIP.  En la l\u00ednea de respuesta se indica el c\u00f3digo de estado de la respuesta que es un  n\u00famero indica el resultado del procesamiento de la  petici\u00f3n. <\/p>\n<p> Los encabezados de peticiones y respuestas se utilizan para diversas funciones del  protocolo relacionadas con el encaminamiento de los mensajes, autenticaci\u00f3n de los  usuarios, entre otras. La extensibilidad del protocolo permite crear nuevos  encabezados para los mensajes agregando de esta manera funcionalidad.  El cuerpo de los mensajes es opcional y se utiliza  entre otras cosas para transportar  las descripciones de las sesiones que se quieren establecer, utilizando la sintaxis del  protocolo SDP.   <\/p>\n<p><strong>Flujo de establecimiento de una sesi\u00f3n<\/strong><\/p>\n<p> El flujo habitual del establecimiento de una sesi\u00f3n mediante el protocolo SIP es el  siguiente, en este ejemplo todos los servidores act\u00faan como proxy:  Un usuario ingresa la direcci\u00f3n l\u00f3gica de la persona con la que quiere comunicarse,  puede indicar al terminal tambi\u00e9n las caracter\u00edsticas de las sesi\u00f3n que quiere  establecer (voz, voz y video, etc.), o estas pueden estar impl\u00edcitas por el tipo de  terminal del que se trate. <\/p>\n<p>El agente de usuario SIP que reside en el terminal,  actuando como UAC env\u00eda la petici\u00f3n (en este caso c on el m\u00e9todo INVITE) al  servidor que tiene configurado. Este servidor se va le del sistema DNS para  determinar la direcci\u00f3n del servidor SIP del dominio del destinatario. El dominio lo  conoce pues es parte de la direcci\u00f3n l\u00f3gica del destinatario. Una vez obtenida la  direcci\u00f3n del servidor del dominio destino, encamina hacia all\u00ed la petici\u00f3n. El  servidor del dominio destino establece que la petici\u00f3n es para un usuario de su  dominio y entonces se vale de la informaci\u00f3n de registraci\u00f3n de dicho usuario para  establecer su ubicaci\u00f3n f\u00edsica. <\/p>\n<p>Si la encuentra, entonces encamina la petici\u00f3n hacia  dicha direcci\u00f3n. El agente de usuario destino si se encuentra desocupado  comenzar\u00e1 a alertar al usuario destino y env\u00eda una  respuesta hacia el usuario  originante con un c\u00f3digo de estado que indica esta  situaci\u00f3n (180 en este caso). <\/p>\n<p>La  respuesta sigue el camino inverso hacia el originan te. Cuando el usuario destino  finalmente acepta la invitaci\u00f3n, se genera una respuesta con un c\u00f3digo de estado  (el 200) que indica que la petici\u00f3n fue aceptada. L a recepci\u00f3n de la respuesta final  es confirmada por el UAC originantem ediante una petici\u00f3n con el m\u00e9todo ACK (de  Acknowledgement), esta petici\u00f3n no genera respuesta s y completa la transacci\u00f3n  de establecimiento de la sesi\u00f3n.  Normalmente la petici\u00f3n con el m\u00e9todo INVITE lleva  un cuerpo donde viaja una  descripci\u00f3n de la sesi\u00f3n que quiere establecer, est a descripci\u00f3n es realizada con el  protocolo SDP.  En ella se indica el tipo de contenido a intercambiar (voz, video,  etc.) y sus caractar\u00edsticas (c\u00f3decs, direcciones, puertos donde se espera recibirlos,  velocidades de transmisi\u00f3n, etc.). Esto se conoce como \u00aboferta de sesi\u00f3n SDP\u00bb. <\/p>\n<p>La  respuesta a esta oferta viaja, en este caso, en el  cuerpo de la respuesta defnitiva a  la petici\u00f3n con el m\u00e9todo INVITE. La misma contiene la descripci\u00f3n de la sesi\u00f3n  desde el punto de vista del destinatario. Si las de scripciones fueran  incompatibles,[7] la sesi\u00f3n debe terminarse (median te una petici\u00f3n con el m\u00e9todo  BYE).  Al terminar la sesi\u00f3n, lo que puede hacer cualquier a de las partes, el agente de  usuario de la parte que termin\u00f3 la sesi\u00f3n, actuando como UAC, env\u00eda hacia la otra  una petici\u00f3n con el m\u00e9todo BYE. Cuando lo recibe el UAS genera la respuesta con el  c\u00f3digo de estado correspondiente.  Si bien se describi\u00f3 el caso de una sesi\u00f3n bipartita, el protocolo permite el  establecimiento de sesiones multipartitas.  Tambi\u00e9n permite que un usuario est\u00e9 registrado en diferentes ubicaciones pudiendo  realizar la b\u00fasqueda en paralelo o secuencial entre todas ellas.    <\/p>\n<p>Tomado de:<br \/>\nArroba, M, &#038; Salazar, M. (2011). Propuesta de soluci\u00f3nes a las vulnerabilidades del protocolo de se\u00f1alizaci\u00f3n SIP en voz sobre IP: Red IP-PBX (tesis de pregrado). Escuela Superior Polit\u00e9cnica de Chimborazo, Riobamba, Ecuador.<\/p>\n<p>Fuente:<br \/>\nhttp:\/\/dspace.espoch.edu.ec\/bitstream\/123456789\/872\/1\/38T00263.pdf<\/p>\n<p>[rev_slider captions]<br \/>\n[rev_slider ServerVoip]<br \/>\n&nbsp;<\/p>\n<hr \/>\n<h2>Contactos<\/h2>\n<p>Obt\u00e9n respuestas sobre tu Empresa Voip. Habla con un asesor especializado para despejar tus inquietudes.<\/p>\n<p><a href=\"http:\/\/www.servervoip.com\/voipswitch\/contacto-server-voip-switch\/\"><img loading=\"lazy\" src=\"http:\/\/www.servervoip.com\/blog\/wp-content\/uploads\/2015\/09\/contacto-servervoip.jpg\" alt=\"contacto servervoip\" width=\"690\" height=\"207\" class=\"aligncenter size-full wp-image-4446\" \/><\/a><br \/>\n<div  data-scroll-reveal=\"ease-in 0px over 0.6s\" ><div  id='elm_5c828b44369b4' class='jsn-bootstrap3 st-element-container clearfix st-element-button text-center' ><script type='text\/javascript'>( function ($) {\n\t\t\t\t$( document ).ready( function () {\n\t\t\t\t\t$( '.st-button-new-window' ).click( function(e){\n\t\t\t\t\t\te.preventDefault();\n\t\t\t\t\t\tvar url = $(this).attr('href');\n\n\t\t\t\t\t\tvar width = screen.availWidth * 0.75;\n\t\t\t\t\t\tvar height = screen.availHeight * 0.75;\n\t\t\t\t\t\tvar left = parseInt((screen.availWidth\/2) - (width\/2));\n\t\t\t\t\t\tvar top = parseInt((screen.availHeight\/2) - (height\/2));\n\t\t\t\t\t\tvar windowFeatures = 'width=' + width + ',height=' + height + ',status,resizable,left=' + left + ',top=' + top + 'screenX=' + left + ',screenY=' + top;\n\t\t\t\t\t\tmyWindow = window.open(url, 'subWind', windowFeatures);\n\t\t\t\t\t} );\n\t\t\t\t});\n\t\t\t})( jQuery )<\/script><a class='btn  btn-icon-text btn-style-default btn-lg  btn-blue st-button-new-window' href='http:\/\/www.servervoip.com\/voipswitch-comprar.php?server=50_promo'><i class='fa fa-shopping-cart'><\/i> SOLICITA TU SERVER AHORA \u25ba<\/a><\/div><\/div><style id=\"style-elm_5c828b44369b4\">#elm_5c828b44369b4  { margin-top: -50px;margin-right: 0px;margin-bottom: -20px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}<\/style><br \/>\n&nbsp;<br \/>\n<strong>ServerVoIP<\/strong> te proporciona todas las herramientas necesarias para que crees y desarrolles <strong>tu negocio de comunicaci\u00f3n por internet.<\/strong><\/p>\n<p>Pertenece al Selecto Grupo de Emprendedores que decidieron cambiar su vida invirtiendo en un <strong>Server con ServerVoIP.<\/strong><\/p>\n<p><strong>ServerVoip <\/strong>presenta el mejor server fisico dedicado para telefonia voip que incluye el software de telefon\u00eda ip \u00abVoipSwitch\u00bb especial para voz sobre ip.<\/p>\n<p><strong>VoipSwitch <\/strong>es la plataforma ideal para que sin necesidad de conocimientos t\u00e9cnicos crees tu propia empresa de Telefon\u00eda IP VoIP y encuentres una forma de ganar DINERO en la red siendo carrier de telefon\u00eda sobre Ip (Voip). <\/p>\n<p>Te brindamos todas las herramientas para que est\u00e9s al nivel de las grandes empresas y negocios; puedas obsequiar llamadas gratis como estrategia de marketing en fidelizaci\u00f3n a tus clientes \/ free entre tus clientes; el servidor VoIP te permite utilizar m\u00faltiples proveedores como nosotros tenemos <a href=\"http:\/\/www.alosip.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.alosip.com.<\/a> (carrier \/ routes) para un mismo destino, vender terminaci\u00f3n (wholesale), clientes finales (retail), etc.<\/p>\n<p>El software te proporciona todo lo que necesitas; sistema llave en mano: para crear tu empresa de telefon\u00eda IP (VoIP) bajo tu propio nombre o marca. M\u00e1s informaci\u00f3n en <a href=\"http:\/\/marcaBlanca.servervoip.com\" target=\"_blank\" rel=\"noopener noreferrer\">marcaBlanca.servervoip.com<\/a><\/p>\n<p>Para que CREES y DESARROLLES tu propia empresa de telefonia por internet, revisa m\u00e1s detalles en <a href=\"http:\/\/www.servervoip.com\/voipswitch\/\">VoIPSwitch<\/a><\/p>\n<hr \/>\n<h1 style=\"text-align: center;\">\u00bfQuieres Emprender por Internet?<\/h1>\n<h3 style=\"text-align: center;\">\u00abAhora Trabajar desde la Comodidad de tu Casa y Ganar Dinero por Internet&#8230; Nunca Hab\u00eda Sido tan F\u00e1cil, R\u00e1pido y con RESULTADOS Impresionantes\u00bb<\/h3>\n<p style=\"text-align: center;\">Descubre el NEGOCIO Perfecto y convi\u00e9rtete en un EMPRESARIO de \u00c9xito creando y desarrollando tu Propia Empresa de Telefon\u00eda por Internet. <strong>Suscr\u00edbete y RECIBE FREE<\/strong>:<\/p>\n<h2 style=\"text-align: center;\">\u00a1Sie7e Poderosas Razones Que Tiene el EMPRENDEDOR Exitoso para Crear su Propia Empresa de Telefon\u00eda por Internet VoIP!&#8230;<\/h2>\n<p><img loading=\"lazy\" class=\"aligncenter wp-image-1229 size-medium\" src=\"http:\/\/servimatango.com\/negocios-rentables\/wp-content\/uploads\/2015\/07\/libro-server-voip-241x300.png\" alt=\"libro server voip\" width=\"241\" height=\"300\" \/><br \/>\n<div  id='elm_5c828b0bd3fa6' class='jsn-bootstrap3 st-element-container clearfix st-element-accordion' style='-moz-border-radius-topleft: 3px;\n-webkit-border-top-left-radius: 3px;\n border-top-left-radius: 3px;; overflow:hidden; '><div class=\"panel-group\" id=\"accordion_kESKVv\">\n\t\t\t<div class='panel panel-default' data-tag=''>\n\t\t\t\t<div class='panel-heading'>\n\t\t\t\t\t<h4 class='panel-title'>\n\t\t\t\t\t\t<a data-toggle='collapse' href='#collapsekESKVv0'>\n\t\t\t\t\t\t\t<i class=''><\/i><img class=aligncenter src=http:\/\/servimatango.com\/negocios-rentables\/wp-content\/uploads\/2015\/07\/Boton-descarga-reporte.gif alt=Reporte width=500 height=145 \/>\n\t\t\t\t\t\t\t<i class='st-icon-accordion'><\/i>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t<\/div>\n\t\t\t\t<div id='collapsekESKVv0' class='panel-collapse collapse '>\n\t\t\t\t  <div class='panel-body'>\n\t\t\t\t  <p><center><script type=\"text\/javascript\" src=\"http:\/\/app.getresponse.com\/view_webform.js?wid=10619501&#038;u=kSvx\"><\/script><\/center><\/p>\n\n\t\t\t\t  <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div><\/div><style id=\"style-elm_5c828b0bd3fa6\">#elm_5c828b0bd3fa6 > .panel-group > .panel > .panel-heading { border-top-right-radius: 0px;border-top-left-radius: 0px;}#elm_5c828b0bd3fa6 > .panel-group > .panel { border-radius: 0px;}#elm_5c828b0bd3fa6  { margin-top: 0px;margin-right: 0px;margin-bottom: 15px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}<\/style><\/p>\n<p><a href=\"http:\/\/www.servervoip.com\/blog\/sip-telefonia\/\">SIP Telefon\u00eda e IVR (Respuesta Autom\u00e1tica)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Formato de los Mensajes: Los mensajes que se intercambian en el protocolo SI P pueden ser peticiones o respuestas. Las peticiones tienen una l\u00ednea de petici\u00f3n, una serie de encabezados y un cuerpo. Las respuestas tienen una l\u00ednea de respuesta, una serie de encabezados y un cuerpo. En la l\u00ednea de petici\u00f3n se indica el&#8230;<\/p>\n<p><a class=\"excerpt-read-more btn btn-primary\" href=\"http:\/\/www.servervoip.com\/blog\/formato-de-los-mensajes\/\" title=\"ReadFormato de los Mensajes\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":[],"categories":[13],"tags":[1876,689,727,291],"aioseo_notices":[],"_links":{"self":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/posts\/6899"}],"collection":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/comments?post=6899"}],"version-history":[{"count":0,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/posts\/6899\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/media?parent=6899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/categories?post=6899"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/tags?post=6899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}