{"id":8253,"date":"2016-09-15T11:37:23","date_gmt":"2016-09-15T16:37:23","guid":{"rendered":"http:\/\/www.servervoip.com\/blog\/?p=8253"},"modified":"2019-06-07T11:06:12","modified_gmt":"2019-06-07T16:06:12","slug":"software-libre-para-telefonia","status":"publish","type":"post","link":"http:\/\/www.servervoip.com\/blog\/software-libre-para-telefonia\/","title":{"rendered":"Software libre para telefon\u00eda"},"content":{"rendered":"<div style=\"display: none;\"\n    class=\"kk-star-ratings kksr-valign-top kksr-align-left kksr-disabled\"\n    data-id=\"8253\"\n    data-slug=\"\">\n    <div class=\"kksr-stars\">\n    <div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n    <\/div>\n    <div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\">\n            <div class=\"kksr-icon\" style=\"width: px; height: px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"kksr-legend\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n<\/div>\n<p><strong>VoIPSwitch: <\/strong> Voipswitch es una plataforma de software que permite a los servicios de VoIP organizar, administrar y gestionr todas las propiedades del servicio de telecomunicacion mediante internet.<\/p>\n<p>Contiene todos los elementos y m\u00f3dulos necesarios en la ejecuci\u00f3n exitosa de varios servicios de VoIP para clientes, proveedores y distribuidores.<br \/>\nVoIP Switch es una plataforma de software completa que permite al emprendedor, crear y desarrollar su propia empresa de telefon\u00eda Voz IP. Contiene todos los elementos necesarios para la gesti\u00f3n de llamadas, distribuci\u00f3n de minutos y venta de varios servicios de VoIP.<\/p>\n<p>El software VoIP Switch ofrece una gran variedad de herramientas para la comunicaci\u00f3n IP, administraci\u00f3n en VSM y m\u00f3dulos para clientes, proveedores y distribuidores; convirtiendo as\u00ed al complemento Server + VoIPSwitch en la soluci\u00f3n completa para el servicio de Telefon\u00eda VoIP a nivel internacional.<\/p>\n<p><strong>ASTERISK <\/strong><\/p>\n<p>Forma parte de una implementaci\u00f3n de \u201cOpen Source\u201d para realizar funciones de una peque\u00f1a central telef\u00f3nica, admitiendo llamadas simult\u00e1neas entre un n\u00famero de usuarios y permitiendo hacer uso de otros servicios telef\u00f3nicos. Software con doble licencia una GNU40 Public Licese y otra comercial, dise\u00f1ado para trabajar con muchos protocolos de VoIP e incluye caracter\u00edsticas IP- PBX como: buz\u00f3n de voz, conferencia de llamadas, respuesta interactivas, entre otras caracter\u00edsticas <\/p>\n<p>Caracter\u00edsticas. <\/p>\n<p>Asterisk de acuerdo (sinologic, 2014) presenta caracter\u00edsticas como las enumeradas a continuaci\u00f3n que hacen de esta plataforma una alternativa muy interesante para VoIP:<br \/>\n\u2022\tSoporte de enlaces digitales RDSI  y CAS.<br \/>\n\u2022\tSoporta fusiones conjuntas a troncales anal\u00f3gicas.<br \/>\n\u2022\tBrinda servicios como Buz\u00f3n de voz, conferencias de voz, colas de llamadas y registro de llamadas detalladas.<br \/>\n\u2022\tAsignaci\u00f3n de categor\u00edas dial plan para servicios locales y celulares.<br \/>\n\u2022\tSoporta protocolos VoIP como SIP, H.323, IAX, MGCP. <\/p>\n<p><strong> Servicios <\/strong><\/p>\n<p>Asterisk incorpora servicios o funcionalidades similares a una peque\u00f1a central convencional y otras m\u00e1s avanzadas las cuales (Quarea, 2014) las describe y se enumeran a continuaci\u00f3n:<br \/>\n\u2022\tTrasferencias: se encarga principalmente de trasferir una llamada en curso a otra extensi\u00f3n de forma directa o previamente una consulta.<br \/>\n\u2022\tDesv\u00edos: permite la trasferencia de una llamada entrante hacia un n\u00famero espec\u00edfico en casos especiales.<br \/>\n\u2022\tConferencia m\u00faltiple: admite la comunicaci\u00f3n entre m\u00faltiples usuarios de la misma central.<br \/>\n\u2022\tCorreo vocal: funciona en casos espec\u00edficos que las llamadas no puedan ser contestadas y son programadas para desviarlas hacia el buz\u00f3n de voz integrado al correo electr\u00f3nico.<br \/>\n\u2022\tM\u00fasica en espera: Asterisk permite introducir m\u00fasica de espera en formatos .wav y mp3. <\/p>\n<p><strong> ELASTIX<\/strong><\/p>\n<p>Elastix corresponde a una soluci\u00f3n de comunicaciones unificadas desarrollada por Palo Santo sobre una plataforma de \u201cSotware Libre\u201d, trabaja bajo c\u00f3digo abierto permitiendo el abaratamiento de costos y mejoras en los servicios. Integra en un solo paquete tecnolog\u00edas como: VoIP PBX, Fax, mensajer\u00eda, email, entre otras; para esto trabaja en conjunto con cuatro programas como: Asterisk, Hylafax, Openfire y Postfix. <\/p>\n<p><strong>Caracter\u00edsticas <\/strong><\/p>\n<p>Elastix presentas las siguientes caracter\u00edsticas en cuanto a funcionamiento como se describe en su p\u00e1gina web:<br \/>\n\u2022\tTiene la capacidad de trabajar simult\u00e1neamente varias m\u00e1quinas virtuales de Elastix sobre un mismo servidor.<br \/>\n\u2022\tPosee una interfaz Web muy amigable para la administraci\u00f3n.<br \/>\n\u2022\tCaracter\u00edsticas de QoS43 propias de la plataforma como cancelaci\u00f3n del eco.<br \/>\n\u2022\tCuenta con un servidor DHCP para la asignaci\u00f3n din\u00e1mica de las direcciones IP.<br \/>\n\u2022\tSoporta diferentes protocolos para VoIP como SIP y IAX entre los principales.<br \/>\n\u2022\tUna de sus ventajas es que puede usar entre algunos codecs de audio como: G.711, G.722, G.729, iLBC, entre otros. <\/p>\n<p><strong>Servicios<\/strong><\/p>\n<p>(Quarea, 2014) enumera los servicios m\u00e1s importantes que brinda Elastix a continuaci\u00f3n: <\/p>\n<p>\u2022\tFax: servidor de fax con acceso desde la web, personalizado, control de acceso y visor de Faxes integrado con descargas en formato PDF.<br \/>\n\u2022\tEmail: servidor administrable desde la Web y soporte multi-dominio.<br \/>\n\u2022\tColaboraci\u00f3n: posee un calendario integrado con funciones de recordatorios de voz y libreta telef\u00f3nica con la capacidad de clic- to- call.<br \/>\n\u2022\tCall Center: est\u00e1 provisto de un m\u00f3dulo de call center con marcador predictivo incluido.<br \/>\n\u2022\tMensajer\u00eda instant\u00e1nea: gracias a programas como OpenFire45 se establece un servidor de mensajer\u00eda que puede ser configurado desde la Web. <\/p>\n<p>[rev_slider captions]<br \/>\n[rev_slider ServerVoip]<br \/>\n&nbsp;<\/p>\n<hr \/>\n<p><strong>TRIXBOX <\/strong><\/p>\n<p>Distribuci\u00f3n del sistema operativo GNU\/Linux basado en Centos46, incluye la implementaci\u00f3n de Asterisk y otra utilidades, software de c\u00f3digo abierto que proporciona beneficios en la reducci\u00f3n de costos y brinda los servicios tanto a la telefon\u00eda tradicional como a la VoIP. <\/p>\n<p><strong>Caracter\u00edsticas <\/strong><\/p>\n<p>A continuaci\u00f3n se enumera las caracter\u00edsticas m\u00e1s importantes de Trixbox: <\/p>\n<p>\u2022\tEs un tipo de distribuci\u00f3n f\u00e1cil de instalar y de operar, usado principalmente por peque\u00f1as empresas.<br \/>\n\u2022\tPosee acceso remoto mediante una plataforma gr\u00e1fica FreePBX47 para la configuraci\u00f3n de manera m\u00e1s f\u00e1cil.<br \/>\n\u2022\tIncorpora est\u00e1ndares tradicionales TDM48 y puertos anal\u00f3gicos FXS y FXO, permitiendo conectarse a las redes p\u00fablicas de telefon\u00eda y redes IP.<br \/>\n\u2022\tEs una plataforma escalable ya que puede ofrecer el servicio desde un m\u00ednimo n\u00famero de usuarios hasta un conjunto totalmente grande de usuarios.<br \/>\n\u2022\tTiene la capacidad de trabajar con protocolos SIP, IAX, H.323, entre otros. <\/p>\n<p><strong>Servicios <\/strong><\/p>\n<p>Trixbox incorpora algunos servicios que se los detalla r\u00e1pidamente a continuaci\u00f3n: <\/p>\n<p>\u2022\tBuz\u00f3n de voz: un sistema de contestador autom\u00e1tico que es personalizado por los usuarios y est\u00e1 vinculado con el correo electr\u00f3nico.<br \/>\n\u2022\tRoom Conference: permite que varios se adhieran a una llamada convirti\u00e9ndola en una conferencia virtual.<br \/>\n\u2022\tIVR: sistema automatizado de respuestas seleccionadas por el usuario de un men\u00fa que le permitir\u00e1n redirigir la llamada a su destino.<br \/>\n\u2022\tCDR: permite detallar las llamadas tanto realizadas como recibidas con fines de costos y facturaci\u00f3n.<br \/>\n\u2022\tACD: sistema autom\u00e1tico de distribuci\u00f3n para caso en los que se presente \u00e1reas de atenci\u00f3n al cliente o soporte t\u00e9cnico. <\/p>\n<p>Tomado de:<br \/>\nMart\u00ednez, M. (2015). Dise\u00f1o del sistema de telefon\u00eda IP bajo una plataforma de software libre para la industria FLORALP S.A. de la ciudad de Ibarra (tesis de pregrado). Universidad T\u00e9cnica del Norte, Ibarra, Ecuador.<br \/>\nFuente:<br \/>\nhttp:\/\/repositorio.utn.edu.ec\/bitstream\/123456789\/4511\/1\/04%20RED%20059%20Tesis.pdf<\/p>\n<h2>Emprendiendo en la Telefon\u00eda por Internet<\/h2>\n<p><a href=\"http:\/\/www.servervoip.com\/voipswitch\"><img loading=\"lazy\" src=\"http:\/\/www.servervoip.com\/blog\/wp-content\/uploads\/empresa-de-telefonia-voip.png\" alt=\"empresa-de-telefonia-voip\" width=\"713\" height=\"449\" class=\"aligncenter size-full wp-image-4717\" \/><\/a><br \/>\n<div  data-scroll-reveal=\"ease-in 0px over 0.6s\" ><div  id='elm_5c828b18cdc55' class='jsn-bootstrap3 st-element-container clearfix st-element-button text-center' ><script type='text\/javascript'>( function ($) {\n\t\t\t\t$( document ).ready( function () {\n\t\t\t\t\t$( '.st-button-new-window' ).click( function(e){\n\t\t\t\t\t\te.preventDefault();\n\t\t\t\t\t\tvar url = $(this).attr('href');\n\n\t\t\t\t\t\tvar width = screen.availWidth * 0.75;\n\t\t\t\t\t\tvar height = screen.availHeight * 0.75;\n\t\t\t\t\t\tvar left = parseInt((screen.availWidth\/2) - (width\/2));\n\t\t\t\t\t\tvar top = parseInt((screen.availHeight\/2) - (height\/2));\n\t\t\t\t\t\tvar windowFeatures = 'width=' + width + ',height=' + height + ',status,resizable,left=' + left + ',top=' + top + 'screenX=' + left + ',screenY=' + top;\n\t\t\t\t\t\tmyWindow = window.open(url, 'subWind', windowFeatures);\n\t\t\t\t\t} );\n\t\t\t\t});\n\t\t\t})( jQuery )<\/script><a class='btn  btn-icon-text btn-style-default btn-lg  btn-blue st-button-new-window' href='http:\/\/www.servervoip.com\/voipswitch-comprar.php?server=50_promo'><i class='fa fa-shopping-cart'><\/i> SOLICITA TU SERVER AHORA \u25ba<\/a><\/div><\/div><style id=\"style-elm_5c828b18cdc55\">#elm_5c828b18cdc55  { margin-top: -50px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}<\/style><br \/>\n&nbsp;<br \/>\nMientras Algunos se pasan Observando los Logros de Otros; T\u00da Trabajas por el Tuyo.<\/p>\n<p>Y T\u00fa, \u00bfTienes lo Que le Hace Falta para Ser un VERDADERO EMPRENDEDOR@?<\/p>\n<p>Tu Empresa de Telefon\u00eda VoIP est\u00e1 dise\u00f1ada para que administres, gestiones y monitorees sus herramientas sin complicaciones o necesidad de conocimientos t\u00e9cnicos.<\/p>\n<ul>\n<li>Genera <strong>CLIENTES<\/strong>,<\/li>\n<li>Ingresa <strong>PROVEEDORES<\/strong>,<\/li>\n<li>Forma <strong>DISTRIBUIDORES<\/strong><\/li>\n<\/ul>\n<p><strong>ServerVoip <\/strong>presenta el mejor server fisico dedicado para telefonia voip que incluye el software de telefon\u00eda ip \u00abVoipSwitch\u00bb especial para voz sobre ip.<\/p>\n<p><strong>VoipSwitch <\/strong>es la plataforma ideal para que sin necesidad de conocimientos t\u00e9cnicos crees tu propia empresa de Telefon\u00eda IP VoIP y encuentres una forma de ganar DINERO en la red siendo carrier de telefon\u00eda sobre Ip (Voip). <\/p>\n<p>Te brindamos todas las herramientas para que est\u00e9s al nivel de las grandes empresas y negocios; puedas obsequiar llamadas gratis como estrategia de marketing en fidelizaci\u00f3n a tus clientes \/ free entre tus clientes; el servidor VoIP te permite utilizar m\u00faltiples proveedores como nosotros tenemos <a href=\"http:\/\/www.alosip.com\/\" target=\"_blank\" rel=\"noopener noreferrer\"> www.alosip.com.<\/a> (carrier \/ routes) para un mismo destino, vender terminaci\u00f3n (wholesale), clientes finales (retail), etc.<\/p>\n<p>El software te proporciona todo lo que necesitas; sistema llave en mano: para crear tu empresa de telefon\u00eda IP (VoIP) bajo tu propio nombre o marca. M\u00e1s informaci\u00f3n en  <a href=\"http:\/\/marcablanca.servervoip.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">marcaBlanca.servervoip.com<\/a><\/p>\n<p>Para que CREES y DESARROLLES tu propia empresa de telefonia por internet, revisa m\u00e1s detalles en <a href=\"http:\/\/www.servervoip.com\/voipswitch\/\">VoIPSwitch<\/a><\/p>\n<hr \/>\n<h1 style=\"text-align: center;\">\u00bfQuieres Emprender por Internet?<\/h1>\n<h3 style=\"text-align: center;\">\u00abAhora Trabajar desde la Comodidad de tu Casa y Ganar Dinero por Internet&#8230; Nunca Hab\u00eda Sido tan F\u00e1cil, R\u00e1pido y con RESULTADOS Impresionantes\u00bb<\/h3>\n<p style=\"text-align: center;\">Descubre el NEGOCIO Perfecto y convi\u00e9rtete en un EMPRESARIO de \u00c9xito creando y desarrollando tu Propia Empresa de Telefon\u00eda por Internet. <strong>Suscr\u00edbete y RECIBE FREE<\/strong>:<\/p>\n<h2 style=\"text-align: center;\">\u00a1Sie7e Poderosas Razones Que Tiene el EMPRENDEDOR Exitoso para Crear su Propia Empresa de Telefon\u00eda por Internet VoIP!&#8230;<\/h2>\n<p><img loading=\"lazy\" class=\"aligncenter wp-image-1229 size-medium\" src=\"http:\/\/servimatango.com\/negocios-rentables\/wp-content\/uploads\/2015\/07\/libro-server-voip-241x300.png\" alt=\"libro server voip\" width=\"241\" height=\"300\" \/><br \/>\n<div  id='elm_5c828b0bd3fa6' class='jsn-bootstrap3 st-element-container clearfix st-element-accordion' style='-moz-border-radius-topleft: 3px;\n-webkit-border-top-left-radius: 3px;\n border-top-left-radius: 3px;; overflow:hidden; '><div class=\"panel-group\" id=\"accordion_vLziEn\">\n\t\t\t<div class='panel panel-default' data-tag=''>\n\t\t\t\t<div class='panel-heading'>\n\t\t\t\t\t<h4 class='panel-title'>\n\t\t\t\t\t\t<a data-toggle='collapse' href='#collapsevLziEn0'>\n\t\t\t\t\t\t\t<i class=''><\/i><img class=aligncenter src=http:\/\/servimatango.com\/negocios-rentables\/wp-content\/uploads\/2015\/07\/Boton-descarga-reporte.gif alt=Reporte width=500 height=145 \/>\n\t\t\t\t\t\t\t<i class='st-icon-accordion'><\/i>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t<\/div>\n\t\t\t\t<div id='collapsevLziEn0' class='panel-collapse collapse '>\n\t\t\t\t  <div class='panel-body'>\n\t\t\t\t  <p><center><script type=\"text\/javascript\" src=\"http:\/\/app.getresponse.com\/view_webform.js?wid=10619501&#038;u=kSvx\"><\/script><\/center><\/p>\n\n\t\t\t\t  <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div><\/div><style id=\"style-elm_5c828b0bd3fa6\">#elm_5c828b0bd3fa6 > .panel-group > .panel > .panel-heading { border-top-right-radius: 0px;border-top-left-radius: 0px;}#elm_5c828b0bd3fa6 > .panel-group > .panel { border-radius: 0px;}#elm_5c828b0bd3fa6  { margin-top: 0px;margin-right: 0px;margin-bottom: 15px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}<\/style><\/p>\n<p><a href=\"http:\/\/www.servervoip.com\/blog\/desventajas-telefonia-ip\/\">Desventajas al Usar la Telefonia por Internet (VoIP)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VoIPSwitch: Voipswitch es una plataforma de software que permite a los servicios de VoIP organizar, administrar y gestionr todas las propiedades del servicio de telecomunicacion mediante internet. Contiene todos los elementos y m\u00f3dulos necesarios en la ejecuci\u00f3n exitosa de varios servicios de VoIP para clientes, proveedores y distribuidores. VoIP Switch es una plataforma de software&#8230;<\/p>\n<p><a class=\"excerpt-read-more btn btn-primary\" href=\"http:\/\/www.servervoip.com\/blog\/software-libre-para-telefonia\/\" title=\"ReadSoftware libre para telefon\u00eda\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":[],"categories":[13],"tags":[1818,780,244,2551,2543,2550,885,1813,353,1136,1020,2548,2544,2547,2545,2546,152,404,1117,2549,1085,157],"aioseo_notices":[],"_links":{"self":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/posts\/8253"}],"collection":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/comments?post=8253"}],"version-history":[{"count":0,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/posts\/8253\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/media?parent=8253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/categories?post=8253"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.servervoip.com\/blog\/wp-json\/wp\/v2\/tags?post=8253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}